{"id":182,"count":13,"description":"","link":"https:\/\/fcg-bielefeld.de\/ru\/series\/26-einzelne-predigten\/","name":"26 - Einzelne Predigten","slug":"26-einzelne-predigten","taxonomy":"wpfc_sermon_series","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_sermon_series\/182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_sermon_series"}],"about":[{"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/taxonomies\/wpfc_sermon_series"}],"wp:post_type":[{"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_sermon?wpfc_sermon_series=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}