{"id":2547,"date":"2018-07-22T06:00:00","date_gmt":"2018-07-22T04:00:00","guid":{"rendered":"https:\/\/fcg-bielefeld.de\/predigt\/1-duerfen-sich-christen-taetowieren-lassen\/"},"modified":"2020-09-03T21:41:28","modified_gmt":"2020-09-03T19:41:28","slug":"1-duerfen-sich-christen-taetowieren-lassen","status":"publish","type":"wpfc_sermon","link":"https:\/\/fcg-bielefeld.de\/ru\/predigt\/1-duerfen-sich-christen-taetowieren-lassen\/","title":{"rendered":"(1) D\u00fcrfen sich Christen t\u00e4towieren lassen?"},"content":{"rendered":"<p>Prediger: Nico Strobel | Series: 18 &#8211; Ich hab da mal &#8217;ne Frage<\/p>","protected":false},"excerpt":{"rendered":"<p>Prediger: Nico Strobel | Series: 18 &#8211; Ich hab da mal &#8217;ne Frage<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","wpfc_preacher":[13],"wpfc_sermon_series":[42],"wpfc_sermon_topics":[],"wpfc_bible_book":[],"wpfc_service_type":[],"class_list":["wpfc_preacher-nico-strobel","wpfc_sermon_series-18-ich-hab-da-mal-ne-frage","wpfc-sermon-single","post-2547","wpfc_sermon","type-wpfc_sermon","status-publish","hentry","no-post-thumbnail"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"sermon_audio":"https:\/\/fcg-bielefeld.de\/wp-content\/uploads\/2018\/07\/2018-07-22_Ich_hab_da_mal_ne_Frage_1_Duerfen_sich_Christen_taetowieren_lassen_Nico_Strobel.mp3","sermon_audio_duration":"","_views":"218","bible_passage":null,"sermon_description":"Ich hab da mal 'ne Frage | Nico Strobel","sermon_video_embed":"","sermon_video_link":"","sermon_bulletin":"","_featured_url":false,"sermon_date":1532239200,"_sermon_date_auto":false,"_links":{"self":[{"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_sermon\/2547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_sermon"}],"about":[{"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/types\/wpfc_sermon"}],"author":[{"embeddable":true,"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/comments?post=2547"}],"version-history":[{"count":0,"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_sermon\/2547\/revisions"}],"wp:attachment":[{"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/media?parent=2547"}],"wp:term":[{"taxonomy":"wpfc_preacher","embeddable":true,"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_preacher?post=2547"},{"taxonomy":"wpfc_sermon_series","embeddable":true,"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_sermon_series?post=2547"},{"taxonomy":"wpfc_sermon_topics","embeddable":true,"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_sermon_topics?post=2547"},{"taxonomy":"wpfc_bible_book","embeddable":true,"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_bible_book?post=2547"},{"taxonomy":"wpfc_service_type","embeddable":true,"href":"https:\/\/fcg-bielefeld.de\/ru\/wp-json\/wp\/v2\/wpfc_service_type?post=2547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}